{"id":877,"date":"2021-01-12T09:24:02","date_gmt":"2021-01-12T08:24:02","guid":{"rendered":"http:\/\/cobomation.de\/?page_id=877"},"modified":"2026-03-03T08:54:27","modified_gmt":"2026-03-03T07:54:27","slug":"nemesys-s","status":"publish","type":"page","link":"https:\/\/cetoni.com\/de\/nemesys-s\/","title":{"rendered":"Nemesys S Spritzenpumpe"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1771313029142{margin-bottom: 30px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h1>Spritzenpumpe<\/h1>\n<h1>Nemesys S<\/h1>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;35&#8243;][nectar_btn size=&#8220;large&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;Handbuch DE&#8220; margin_right=&#8220;5&#8243; url=&#8220;https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys_S_DE.pdf&#8220; icon_fontawesome=&#8220;fa fa-cloud-download&#8220;][nectar_btn size=&#8220;large&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;Handbuch EN&#8220; margin_right=&#8220;5&#8243; url=&#8220;https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys_S_EN.pdf&#8220; icon_fontawesome=&#8220;fa fa-cloud-download&#8220;][nectar_btn size=&#8220;large&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;fontawesome&#8220; text=&#8220;Datenblatt&#8220; margin_top=&#8220;0&#8243; margin_right=&#8220;5&#8243; url=&#8220;https:\/\/cetoni.de\/downloads\/datasheets\/Datasheet_Nemesys_S.pdf&#8220; icon_fontawesome=&#8220;fa fa-cloud-download&#8220; margin_bottom=&#8220;20&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding_phone=&#8220;30&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;4888&#8243; image_size=&#8220;full&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1762270160444{margin-bottom: 30px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h2>Pulsationsfrei | 8 pl\/min &#8211; 150 ml\/min | 0 &#8211; 10 bar | Kontinuierlicher Fluss | Modular | Softwaresteuerung | Druckmessung<\/h2>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;8150&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;350&#8243;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3>CETONI Nemesys S Spritzenpumpe &#8211; Perfektion bis ins kleinste Detail<\/h3>\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-3\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"22f8efdc-ff30-439b-b47b-d8e1a1a23344\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<p>Arbeiten Sie in Forschung und Entwicklung und sto\u00dfen bei herk\u00f6mmlichen F\u00f6rdersystemen auf Grenzen? Dann ist ein flexibles Flow-System mit CETONI Nemesys S Spritzenpumpen die perfekte L\u00f6sung f\u00fcr Ihre anspruchsvollen Dosieraufgaben!<\/p>\n<p>Unsere Nemesys Spritzenpumpen wurden auf Basis jahrelanger Erfahrung und Kundenfeedbacks weiterentwickelt. Das Ergebnis ist ein neues Niveau an Pr\u00e4zision und Zuverl\u00e4ssigkeit, das Ihre Arbeit erheblich erleichtert.<\/p>\n<p>Die verbesserten Nemesys S und M Spritzenpumpen bieten au\u00dfergew\u00f6hnliche Pulsationsfreiheit, was zu einer besonders gleichm\u00e4\u00dfigen pulsationsfreien Dosierung f\u00fchrt. So k\u00f6nnen Sie sich auf eine konstante und pr\u00e4zise Flie\u00dfrate von bis zu 8 pl\/min bis hin zu 150 ml\/min verlassen, was in vielen Anwendungen von entscheidender Bedeutung ist. Neue Sicherheitsfeatures und intelligente Ventiltechnik sorgen daf\u00fcr, dass Sie auch komplexe Dosieraufgaben m\u00fchelos und sicher bei bis zu 10 bar Anwendungsdruck bew\u00e4ltigen k\u00f6nnen. Mit der flexiblen Einbau- und Steuereungsm\u00f6glichkeit (PC oder Anlagenintegration) passen sich die Pumpen perfekt an Ihre individuellen Anforderungen an.<\/p>\n<p>Erleben Sie, wie die CETONI Nemesys Spritzenpumpen Ihre Forschung und Entwicklung softwaregesteuert auf das n\u00e4chste Level heben!<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][toggles style=&#8220;default&#8220; border_radius=&#8220;none&#8220;][toggle color=&#8220;Default&#8220; heading_tag=&#8220;span&#8220; heading_tag_functionality=&#8220;default&#8220; title=&#8220;Warum pulsationsfrei?&#8220;][vc_column_text css_animation=&#8220;appear&#8220; css=&#8220;&#8220; text_direction=&#8220;default&#8220;]Mikrofluidik arbeitet mit kleinsten Str\u00f6men in winzigen Kavit\u00e4ten. F\u00fcr Anwendungen wie Flow-Chemie und Biochemie sind gleichm\u00e4\u00dfige, pulsationsfreie Fl\u00fcssigkeitsstr\u00f6me entscheidend, um konstante Mischverh\u00e4ltnisse und pr\u00e4zise Str\u00f6mungen zu gew\u00e4hrleisten.<\/p>\n<p>Pulsationen sind Schwankungen in der Flussrate, die bei extrem kleinen Str\u00f6mungen in der Mikrofluidik problematisch sein k\u00f6nnen. Absolute Pulsationsfreiheit ist technisch nicht m\u00f6glich, aber wir k\u00f6nnen die Pulsationen so weit reduzieren, dass sie keine messbaren Auswirkungen mehr haben.<\/p>\n<p>CETONI verwendet hochwertige Komponenten und pr\u00e4zise Antriebe in unseren Spritzenpumpen, um Pulsationen auf ein Minimum zu reduzieren. Unsere Nemesys Spritzenpumpen bieten dadurch die extreme Genauigkeit, die f\u00fcr mikrofluidische Anwendungen erforderlich ist.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8142 aligncenter\" src=\"https:\/\/cetoni.de\/wp-content\/uploads\/pulsationsfrei-vs-pulsationen-300x152.png\" alt=\"pulsationsfrei versus pulsationen im fluss\" width=\"748\" height=\"379\" srcset=\"https:\/\/cetoni.com\/wp-content\/uploads\/pulsationsfrei-vs-pulsationen-300x152.png 300w, https:\/\/cetoni.com\/wp-content\/uploads\/pulsationsfrei-vs-pulsationen-1024x517.png 1024w, https:\/\/cetoni.com\/wp-content\/uploads\/pulsationsfrei-vs-pulsationen-768x388.png 768w, https:\/\/cetoni.com\/wp-content\/uploads\/pulsationsfrei-vs-pulsationen.png 1259w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/p>\n<p>Mikrofluidische Anwendungen, bei denen eine pulsationsfreie Dosierung entscheidend ist:<\/p>\n<p><strong>Biologie<\/strong>: Bei der Analyse und Sortierung von Zellen erfordert die Erstellung von Einzelzell-Analysen einen konstanten und pulsationsfreien Fluss, um die Zellen pr\u00e4zise zu manipulieren und zu untersuchen.<\/p>\n<p><strong>Chemie<\/strong>: In der Flow-Chemie ist eine gleichm\u00e4\u00dfige Durchflussrate entscheidend f\u00fcr die Reproduzierbarkeit von Reaktionen und die genaue Kontrolle von Mischungsverh\u00e4ltnissen, was zu konsistenten und zuverl\u00e4ssigen Ergebnissen f\u00fchrt.<\/p>\n<p><strong>Industrie<\/strong>: Bei der Herstellung von mikrostrukturierten Materialien und Sensoren oder homogenen Schichten, m\u00fcssen Fl\u00fcssigkeiten pr\u00e4zise und gleichm\u00e4\u00dfig dosiert werden, um die gew\u00fcnschte Struktur und Funktionalit\u00e4t sicherzustellen.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;column_reverse&#8220; column_direction_phone=&#8220;column_reverse&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.5&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Damit Sie sich auf Ihre Forschung konzentrieren k\u00f6nnen<\/h3>\n<p>Die hochpr\u00e4zise und gleichzeitig pulsationsfreie Dosierung von Fl\u00fcssigkeiten im Mikro- und Nanoliterma\u00dfstab stellt h\u00f6chste Anforderungen an die verwendete Pumpentechnik. Im Bereich der Biologie und Biochemie kommt es dabei nicht auf hohe Dr\u00fccke an, daf\u00fcr aber umso mehr auf ein sehr homogenes Flie\u00dfverhalten, auch bei niedrigsten Flussraten, sowie ein schnelles Ansprechverhalten bei Flussraten\u00e4nderungen. Diese Kerneigenschaften haben wir bei unseren CETONI Nemesys S und M Spritzenpumpen so optimiert, dass Sie damit sehr einfach perfekte Ergebnisse erzielen.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;3422&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;350&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;4598&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;350&#8243;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Let it Flow<\/h3>\n<p>Viele fluidische Prozesse, die herk\u00f6mmlich im Batch-Verfahren durchgef\u00fchrt wurden, lassen sich in fortschrittliche Flow Prozesse \u00fcberf\u00fchren und bieten dabei eine Menge Vorteile gegen\u00fcber den konservativen Ans\u00e4tzen, wie z.B. hohe Prozesssicherheit, homogene Reaktionsbedingungen, Zeit- und Ressourceneinsparung. Die Anwendungsgebiete erstrecken sich dabei von der Biologie \u00fcber die Chemie bis hin zur Physik in unterschiedlichen Anwendungsszenarien, welche wir f\u00fcr Sie unter <a href=\"https:\/\/cetoni.de\/application-notes\/\">Application Notes<\/a> anschaulich beschrieben haben.<\/p>\n<p>Wir zeigen Ihnen auf, wie Sie Ihren Batch-Prozess in einen fortschrittlichen Flow Prozess \u00fcberf\u00fchren k\u00f6nnen oder bisher manuelle Laborprozesse mithilfe von <a href=\"https:\/\/cetoni.com\/de\/cobomation\/\">Cobomation<\/a> automatisieren k\u00f6nnen. Sprechen Sie uns einfach an![\/vc_column_text][nectar_btn size=&#8220;medium&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;Mehr zu Cobomation &gt;&gt;&#8220; margin_top=&#8220;5&#8243; margin_right=&#8220;5&#8243; url=&#8220;https:\/\/cetoni.de\/cobomation&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; equal_height=&#8220;yes&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;2877&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;250&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;top&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;3044&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;250&#8243;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;2881&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; offset=&#8220;vc_hidden-sm vc_hidden-xs&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;250&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;30&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h2>Software &amp; Zubeh\u00f6r<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_b_to_right_t&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;2744&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; enable_gradient=&#8220;true&#8220; color_overlay_2=&#8220;#1b93f0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;450&#8243;][\/vc_column][vc_column column_padding=&#8220;padding-6-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;rgba(197,208,221,0.19)&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\"><\/div>\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-3\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ccf39b0e-8172-447d-a350-2087a898d0e7\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<h3>Intuitive Bedienung, flexible Automatisierung und m\u00fchelose Integration<\/h3>\n<p>Mit der <a href=\"https:\/\/cetoni.com\/de\/cetoni-elements\/\">CETONI Elements<\/a> Software steuern Sie Ihre Spritzenpumpen intuitiv und automatisieren Flow-Prozesse unkompliziert, um schnell aussagekr\u00e4ftige Ergebnisse zu erzielen.<\/p>\n<p>Unser umfangreiches <a href=\"https:\/\/cetoni.de\/cetoni-sdk-linux-phyton\/\">CETONI SDK<\/a> f\u00fcr Windows und Linux erm\u00f6glicht die nahtlose Integration Ihres Spritzenpumpensystems in Ihre bevorzugten Softwareumgebungen wie C++, Python oder LabView.<\/p>\n<p>Entdecken Sie die M\u00f6glichkeiten unserer Software und optimieren Sie Ihre mikrofluidischen Prozesse f\u00fcr maximale Effizienz und Pr\u00e4zision.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;CETONI Elements &gt;&gt;&#8220; url=&#8220;https:\/\/cetoni.de\/cetoni-elements\/&#8220; margin_right=&#8220;20&#8243;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;CETONI SDK &gt;&gt;&#8220; url=&#8220;https:\/\/cetoni.de\/cetoni-sdk&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;video_halterung_s&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_b_to_right_t&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_video_player_self_hosted video_mp4=&#8220;https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Animation-Spritzenwechsel-und-Modifikation-1.mp4&#8243; video_image=&#8220;8147&#8243; player_functionality=&#8220;default&#8220; loop=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; advanced_gradient_display_type=&#8220;linear&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-6-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;rgba(197,208,221,0.19)&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-3\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"dd6ace37-1adc-49d2-854b-6291e4a6763f\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<h3>Flexible Ventill\u00f6sungen und Drucksensoren f\u00fcr Nemesys S<\/h3>\n<p>Die Nemesys Spritzenpumpe bietet dank ihres volumetrischen F\u00f6rderprinzips und der einfachen Bedienung erhebliche Vorteile f\u00fcr mikrofluidische Anwendungen. Ein h\u00e4ufig genannter Nachteil ist das Ende der F\u00f6rderung, sobald die Spritze leer ist. Mit unseren modularen Systemen l\u00e4sst sich dieses Problem elegant l\u00f6sen: Setzen Sie pro Dosierkanal zwei Nemesys Spritzenpumpen ein, die abwechselnd arbeiten.<\/p>\n<p>Unsere Drucksensoren sch\u00fctzen nicht nur Ihre Anwendung und den Anwender, sondern liefern auch wertvolle Daten zur \u00dcberwachung und Beurteilung Ihres Prozesses. So erhalten Sie eine l\u00fcckenlose Kontrolle und k\u00f6nnen Ihre mikrofluidischen Anwendungen optimal steuern und \u00fcberwachen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;Ventile und Drucksensoren &gt;&gt;&#8220; url=&#8220;https:\/\/cetoni.de\/ventile\/&#8220; margin_right=&#8220;20&#8243;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;Spritzenhalter &gt;&gt;&#8220; url=&#8220;https:\/\/cetoni.de\/sonstiges-zubehoer\/&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;20&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_b_to_right_t&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;3424&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; enable_gradient=&#8220;true&#8220; color_overlay_2=&#8220;#1b93f0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;450&#8243;][\/vc_column][vc_column column_padding=&#8220;padding-6-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;rgba(197,208,221,0.19)&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h3>Pr\u00e4zisions-Glasspritzen f\u00fcr Nemesys S Spritzenpumpen<\/h3>\n<p>Basierend auf dem Feedback unserer Kunden und unseren Erfahrungen, haben wir zusammen mit dem Know-How unseres Partners SETonic GmbH (Ilmenau, Deutschland) eine zuverl\u00e4ssige und einfach zu handhabende Pr\u00e4zisionsspritzenserie entwickelt, welche optimal zu unseren Produkten und dem Anspruch unserer Kunden passt.[\/vc_column_text][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; text=&#8220;Glasspritzen\u00fcbersicht &gt;&gt;&#8220; url=&#8220;https:\/\/cetoni.de\/spritzen\/&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;top&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h2>Branchen und Anwendungen<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;blogunten&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][recent_posts style=&#8220;classic_enhanced&#8220; color_scheme=&#8220;light&#8220; columns=&#8220;3&#8243; category=&#8220;branchen&#8220; order=&#8220;DESC&#8220; orderby=&#8220;rand&#8220; blog_remove_post_date=&#8220;true&#8220; blog_remove_post_author=&#8220;true&#8220; blog_remove_post_comment_number=&#8220;true&#8220; blog_remove_post_nectar_love=&#8220;true&#8220; posts_per_page=&#8220;3&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;top&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Sie haben Fragen?<\/h3>\n<h2><a href=\"+493660233880\">+49 (0) 36602 338-80<\/a><\/h2>\n<p><a href=\"mailto:application@cetoni.de\">application@cetoni.de<\/a>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3044,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-877","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung<\/title>\n<meta name=\"description\" content=\"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cetoni.com\/de\/nemesys-s\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung\" \/>\n<meta property=\"og:description\" content=\"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cetoni.com\/de\/nemesys-s\/\" \/>\n<meta property=\"og:site_name\" content=\"CETONI GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T07:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Valve_side_view.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/\",\"url\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/\",\"name\":\"CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cetoni.com\\\/wp-content\\\/uploads\\\/Nemeys_S_Valve_side_view.jpg\",\"datePublished\":\"2021-01-12T08:24:02+00:00\",\"dateModified\":\"2026-03-03T07:54:27+00:00\",\"description\":\"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cetoni.com\\\/wp-content\\\/uploads\\\/Nemeys_S_Valve_side_view.jpg\",\"contentUrl\":\"https:\\\/\\\/cetoni.com\\\/wp-content\\\/uploads\\\/Nemeys_S_Valve_side_view.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Spritzenpumpe Nemesys S, syringe pump Nemesys S\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/nemesys-s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cetoni.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nemesys S Spritzenpumpe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cetoni.com\\\/de\\\/\",\"name\":\"CETONI GmbH\",\"description\":\"Automatisierungs- und Mikrofluidikl\u00f6sungen f\u00fcr das Labor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cetoni.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung","description":"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cetoni.com\/de\/nemesys-s\/","og_locale":"de_DE","og_type":"article","og_title":"CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung","og_description":"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.","og_url":"https:\/\/cetoni.com\/de\/nemesys-s\/","og_site_name":"CETONI GmbH","article_modified_time":"2026-03-03T07:54:27+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Valve_side_view.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cetoni.com\/de\/nemesys-s\/","url":"https:\/\/cetoni.com\/de\/nemesys-s\/","name":"CETONI Nemesys S Spritzenpumpe f\u00fcr pulsationsfreie F\u00f6rderung","isPartOf":{"@id":"https:\/\/cetoni.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cetoni.com\/de\/nemesys-s\/#primaryimage"},"image":{"@id":"https:\/\/cetoni.com\/de\/nemesys-s\/#primaryimage"},"thumbnailUrl":"https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Valve_side_view.jpg","datePublished":"2021-01-12T08:24:02+00:00","dateModified":"2026-03-03T07:54:27+00:00","description":"CETONI Nemesys S Spritzenpumpe, Software-gesteuert, Ventile und optimierte Glasspritzen f\u00fcr pulsationsfreie Medienversorgung Ihrer Anwendung.","breadcrumb":{"@id":"https:\/\/cetoni.com\/de\/nemesys-s\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cetoni.com\/de\/nemesys-s\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cetoni.com\/de\/nemesys-s\/#primaryimage","url":"https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Valve_side_view.jpg","contentUrl":"https:\/\/cetoni.com\/wp-content\/uploads\/Nemeys_S_Valve_side_view.jpg","width":1920,"height":1080,"caption":"Spritzenpumpe Nemesys S, syringe pump Nemesys S"},{"@type":"BreadcrumbList","@id":"https:\/\/cetoni.com\/de\/nemesys-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cetoni.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nemesys S Spritzenpumpe"}]},{"@type":"WebSite","@id":"https:\/\/cetoni.com\/de\/#website","url":"https:\/\/cetoni.com\/de\/","name":"CETONI GmbH","description":"Automatisierungs- und Mikrofluidikl\u00f6sungen f\u00fcr das Labor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cetoni.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":29,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/877\/revisions"}],"predecessor-version":[{"id":8943,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/877\/revisions\/8943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/media\/3044"}],"wp:attachment":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/media?parent=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}