{"id":388,"date":"2020-12-21T17:45:11","date_gmt":"2020-12-21T16:45:11","guid":{"rendered":"http:\/\/cobomation.de\/?page_id=388"},"modified":"2026-02-17T11:57:19","modified_gmt":"2026-02-17T10:57:19","slug":"anleitungen","status":"publish","type":"page","link":"https:\/\/cetoni.com\/de\/anleitungen\/","title":{"rendered":"Anleitungen"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;padding-3-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;top&#8220; top_margin=&#8220;0&#8243; bottom_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243; bottom_margin_phone=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h1>Anleitungen Produkte<\/h1>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; bottom_padding_tablet=&#8220;0&#8243; bottom_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;anleitung_software&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; top_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243; bottom_margin_phone=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1660139367725{padding-top: 10px !important;}&#8220;]\n<h2>Software<\/h2>\n<p>&nbsp;<\/p>\n<h3>CETONI Elements Software<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-book accent-color\"><\/i> CETONI Elements Online Handbuch (HTML) (<a href=\"https:\/\/cetoni-software.github.io\/cetoni_elements_doc\/manual_de\/\">DE<\/a> \/ <a href=\"https:\/\/cetoni-software.github.io\/cetoni_elements_doc\/manual_en\/\">EN<\/a>)<\/li>\n<\/ul>\n<h3>Software Development Kit (SDK)<\/h3>\n<ul>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/CETONI_SDK\/index.html\"><i class=\"icon-normal fa fa-book accent-color\"><\/i> CETONI SDK Online Dokumentation (HTML) (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/CETONI_SDK_HTML_Reference.zip\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> CETONI SDK HTML Dokumentation (HTML) (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Nemesys_SDK\/index.html\"><i class=\"icon-normal fa fa-book accent-color\"><\/i> Nemesys SDK Online Dokumentation (HTML) (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Nemesys_RS232_Library\/index.html\"><i class=\"icon-normal fa fa-book accent-color\"><\/i> Nemesys RS232 Online Dokumentation (HTML) (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Nemesys_Integration_Kit.zip\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys Integration Kit (SPS, Mikrokontroller)<\/a><\/li>\n<\/ul>\n<h3>Firmware<\/h3>\n<ul>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/neMESYS_Firmware_Specification.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys Firmware Specification (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/EPOS2-Firmware-Specification-En.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys Drive (EPOS2) Firmware Specification (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/NemesysV4_Firmware_Specification.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys V4 Firmware Specification (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/EPOS4-Firmware-Specification.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys V4 Drive (EPOS4) Firmware Specification (EN)<\/a><\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/manuals\/CHANGE NOTICE NEMESYS 4 Communication Protocol.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Nemesys V4 change note (EN)<\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; bottom_padding_tablet=&#8220;0&#8243; bottom_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;anleitung_hardware&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; top_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243; bottom_margin_phone=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1637829361469{padding-top: 10px !important;}&#8220;]\n<h2>Ger\u00e4te<\/h2>\n<p>&nbsp;<\/p>\n<h3>Systemhandbuch<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Systemhandbuch (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_CETONI_System_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_CETONI_System_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n<h3>Nemesys Spritzenpumpen<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Nemesys S (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys_S_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys_S_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Nemesys M (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys_M_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys_M_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Nemesys Hochdruckmodul (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys_Hochdruck_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys_HighPressure_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Nemesys Ultra-Hochdruckmodul (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys-XL_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys-XL_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; bottom_padding_tablet=&#8220;0&#8243; bottom_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;#anleitung_hardware&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; top_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243; bottom_margin_phone=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1770630010173{padding-top: 10px !important;}&#8220; text_direction=&#8220;default&#8220;]\n<h3>Basismodule<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Base (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Basismodule_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Base_Modules_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n<h3>I\/O-Modul<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch I\/O (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_QmixIO-B_Modul_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_QmixIO-B_Module_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n<h3>Spritzenr\u00fchrer Nemix 50<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Nemix 50 Spritzenr\u00fchrer (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemix_50_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemix_50_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n<h3>Sonstiges Zubeh\u00f6r<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch Ultra-Hochdruckspritzen (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Spritzen_neMESYS_XL_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Syringes_neMESYS_XL_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch 3\/4-Wege Contiflow-Ventil f\u00fcr Nemesys S (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Nemesys_S_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Nemesys_S_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch 3\/3-Wege Hochdruck-Contiflow-Ventil (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Contiflow_Kugelhahnventil_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Contiflow_Ballvalve_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch 3\/3-Wege Hochdruck-Kugelhahnventil (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Contiflow_Kugelhahnventil_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_Contiflow_Ballvalve_EN.pdf\">EN<\/a>)<\/li>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Handbuch externer Druckmesser (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Handbuch_Hardware_Externer_Drucksensor_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/Manual_Hardware_External_Pressure_Sensor_EN.pdf\">EN<\/a>)<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; bottom_padding=&#8220;0&#8243; bottom_padding_tablet=&#8220;0&#8243; bottom_padding_phone=&#8220;0&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; id=&#8220;anleitung_service&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#ffffff&#8220; color_overlay_2=&#8220;#d0dae3&#8243; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-4-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; top_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243; bottom_margin_phone=&#8220;0&#8243; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;.vc_custom_1661846549299{padding-top: 10px !important;}&#8220;]\n<h2>Inbetriebnahme &amp; Service<\/h2>\n<p>&nbsp;<\/p>\n<h3>Service Tool<\/h3>\n<ul>\n<li><a href=\"https:\/\/cetoni-software.github.io\/cetoni_service_guide\/\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-book accent-color\"><\/i> Nemesys \/ Qmix Online Service Guide (HTML) (EN)<\/a><\/li>\n<\/ul>\n<h3>Versand<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Dekontaminationserkl\u00e4rung f\u00fcr Ger\u00e4ter\u00fcckversand (<a href=\"https:\/\/cetoni.de\/downloads\/Dekontaminationserklaerung.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/Declaration-of-Decontamination.pdf\">EN<\/a>)<\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/LS14500-UN38.3-Test-Summary-Report.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Batterieinformation f\u00fcr Nemesys S und M (EN)<\/a><\/li>\n<\/ul>\n<h3>Quickstart &amp; Connectivity Guide<\/h3>\n<ul>\n<li><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Quickstart Guide (<a href=\"https:\/\/cetoni.de\/downloads\/manuals\/QuickstartGuide_DE.pdf\">DE<\/a> \/ <a href=\"https:\/\/cetoni.de\/downloads\/manuals\/QuickstartGuide_EN.pdf\">EN<\/a>)<\/li>\n<li><a href=\"https:\/\/cetoni.de\/downloads\/Connectivity-Guide.pdf\" target=\"_blank\" rel=\"noopener\"><i class=\"icon-normal fa fa-cloud-download accent-color\"><\/i> Connectivity Guide (EN)<\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;5%&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-5-percent&#8220; column_padding_tablet=&#8220;padding-5-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][vc_column_text]\n<h2>Sie haben Fragen zu Anleitungen?<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;20px&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_b_to_right_t&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;6635&#8243; background_image_type=&#8220;default&#8220; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; enable_bg_scale=&#8220;true&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; enable_gradient=&#8220;true&#8220; color_overlay_2=&#8220;#1b93f0&#8243; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;250&#8243;][\/vc_column][vc_column column_padding=&#8220;padding-6-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;rgba(197,208,221,0.19)&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]Kontaktieren Sie uns, wir beraten Sie gern!<\/p>\n<h3>Applikation &amp; Support<\/h3>\n<ul>\n<li>+49 (0) 36602 338-80<\/li>\n<li><a title=\"E-Mail Christian Kirscht\" href=\"mailto:application@cetoni.de?subject=support request\">application@cetoni.de<\/a><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;none&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;padding-2-percent&#8220; column_padding_tablet=&#8220;padding-3-percent&#8220; column_padding_phone=&#8220;padding-5-percent&#8220; column_padding_position=&#8220;top&#8220; top_margin=&#8220;0&#8243; bottom_margin=&#8220;0&#8243; top_margin_tablet=&#8220;0&#8243; bottom_margin_tablet=&#8220;0&#8243; top_margin_phone=&#8220;0&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-388","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys<\/title>\n<meta name=\"description\" content=\"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cetoni.com\/de\/anleitungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys\" \/>\n<meta property=\"og:description\" content=\"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cetoni.com\/de\/anleitungen\/\" \/>\n<meta property=\"og:site_name\" content=\"CETONI GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T10:57:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/anleitungen\\\/\",\"url\":\"https:\\\/\\\/cetoni.com\\\/de\\\/anleitungen\\\/\",\"name\":\"Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/#website\"},\"datePublished\":\"2020-12-21T16:45:11+00:00\",\"dateModified\":\"2026-02-17T10:57:19+00:00\",\"description\":\"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/anleitungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cetoni.com\\\/de\\\/anleitungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/anleitungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cetoni.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anleitungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cetoni.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cetoni.com\\\/de\\\/\",\"name\":\"CETONI GmbH\",\"description\":\"Automatisierungs- und Mikrofluidikl\u00f6sungen f\u00fcr das Labor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cetoni.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys","description":"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cetoni.com\/de\/anleitungen\/","og_locale":"de_DE","og_type":"article","og_title":"Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys","og_description":"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download","og_url":"https:\/\/cetoni.com\/de\/anleitungen\/","og_site_name":"CETONI GmbH","article_modified_time":"2026-02-17T10:57:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cetoni.com\/de\/anleitungen\/","url":"https:\/\/cetoni.com\/de\/anleitungen\/","name":"Anleitungen und Handb\u00fccher f\u00fcr CETONI Produkte und Nemesys","isPartOf":{"@id":"https:\/\/cetoni.com\/de\/#website"},"datePublished":"2020-12-21T16:45:11+00:00","dateModified":"2026-02-17T10:57:19+00:00","description":"Anleitungen und Software Dokumentationen f\u00fcr CETONI Module, Hardware und Software Applikationen zum Download","breadcrumb":{"@id":"https:\/\/cetoni.com\/de\/anleitungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cetoni.com\/de\/anleitungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cetoni.com\/de\/anleitungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cetoni.com\/de\/"},{"@type":"ListItem","position":2,"name":"Anleitungen"}]},{"@type":"WebSite","@id":"https:\/\/cetoni.com\/de\/#website","url":"https:\/\/cetoni.com\/de\/","name":"CETONI GmbH","description":"Automatisierungs- und Mikrofluidikl\u00f6sungen f\u00fcr das Labor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cetoni.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":7,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/388\/revisions"}],"predecessor-version":[{"id":8895,"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/pages\/388\/revisions\/8895"}],"wp:attachment":[{"href":"https:\/\/cetoni.com\/de\/wp-json\/wp\/v2\/media?parent=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}